{"id":89,"count":257,"description":"","link":"http:\/\/vietqualitytravel.com\/index.php\/category\/news\/","name":"News","slug":"news","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/vietqualitytravel.com\/index.php\/wp-json\/wp\/v2\/categories\/89"}],"collection":[{"href":"http:\/\/vietqualitytravel.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/vietqualitytravel.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/vietqualitytravel.com\/index.php\/wp-json\/wp\/v2\/posts?categories=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}